{"id":24103,"date":"2026-07-14T13:57:22","date_gmt":"2026-07-14T11:57:22","guid":{"rendered":"https:\/\/ciriecstat.com\/serie\/2-7-2-sociedades-laborales-registradas-por-tipo-de-sociedad-y-provincia\/"},"modified":"2026-07-14T13:58:56","modified_gmt":"2026-07-14T11:58:56","slug":"2-7-2-sociedades-laborales-registradas-por-tipo-de-sociedad-y-provincia","status":"publish","type":"series","link":"https:\/\/ciriecstat.com\/en\/serie\/2-7-2-sociedades-laborales-registradas-por-tipo-de-sociedad-y-provincia\/","title":{"rendered":"Sociedades Laborales registradas por tipo de sociedad y Provincia. 1999-2024"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"series_tipo_de_series":[411],"series_tipo_region":[561],"series_regimen_cotizacion":[],"series_provincia":[364,351,352,353,354,355,356,357,358,359,360,361,362,363,350,365,366,367,368,369,370,371,372,373,374,375,376,337,325,326,327,328,329,330,331,332,333,334,335,336,324,338,339,340,341,342,343,344,345,346,347,348,349],"series_comunidad_autonoma":[],"series_periodo":[313,630,609,470,469,468,320,319,318,317,316,315,314,300,312,311,310,309,308,307,306,305,304,303,302,301],"series_entidades_empleo":[],"series_empleo_centros_cotiz":[],"series_division_actividad":[],"series_tipo_cooperativa":[],"series_sexo":[],"series_sector_actividad":[],"series_tipo_socio":[],"series_tipo_sociedad":[454,455,456],"series_entidades_socios_ini":[],"series_tipo_socio_slab":[],"class_list":["post-24103","series","type-series","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series\/24103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series"}],"about":[{"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/types\/series"}],"wp:attachment":[{"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/media?parent=24103"}],"wp:term":[{"taxonomy":"series_tipo_de_series","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_de_series?post=24103"},{"taxonomy":"series_tipo_region","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_region?post=24103"},{"taxonomy":"series_regimen_cotizacion","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_regimen_cotizacion?post=24103"},{"taxonomy":"series_provincia","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_provincia?post=24103"},{"taxonomy":"series_comunidad_autonoma","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_comunidad_autonoma?post=24103"},{"taxonomy":"series_periodo","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_periodo?post=24103"},{"taxonomy":"series_entidades_empleo","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_entidades_empleo?post=24103"},{"taxonomy":"series_empleo_centros_cotiz","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_empleo_centros_cotiz?post=24103"},{"taxonomy":"series_division_actividad","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_division_actividad?post=24103"},{"taxonomy":"series_tipo_cooperativa","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_cooperativa?post=24103"},{"taxonomy":"series_sexo","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_sexo?post=24103"},{"taxonomy":"series_sector_actividad","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_sector_actividad?post=24103"},{"taxonomy":"series_tipo_socio","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_socio?post=24103"},{"taxonomy":"series_tipo_sociedad","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_sociedad?post=24103"},{"taxonomy":"series_entidades_socios_ini","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_entidades_socios_ini?post=24103"},{"taxonomy":"series_tipo_socio_slab","embeddable":true,"href":"https:\/\/ciriecstat.com\/en\/wp-json\/wp\/v2\/series_tipo_socio_slab?post=24103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}